{"id":370,"date":"2016-02-04T08:25:21","date_gmt":"2016-02-04T08:25:21","guid":{"rendered":"http:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization.jpg"},"modified":"2016-02-04T08:25:21","modified_gmt":"2016-02-04T08:25:21","slug":"radicalization","status":"inherit","type":"attachment","link":"https:\/\/blogg.hiof.no\/fro\/radicalization\/","title":{"rendered":"Radicalization"},"author":243,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-370","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a7dWEJ-5Y","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"160\" src=\"https:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization-300x160.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization-300x160.jpg 300w, https:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization.jpg 500w\" sizes=\"auto, 100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":500,"height":266,"file":"2016\/02\/Radicalization.jpg","sizes":{"thumbnail":{"file":"Radicalization-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization-150x150.jpg"},"medium":{"file":"Radicalization-300x160.jpg","width":300,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization-300x160.jpg"},"post-thumbnail":{"file":"Radicalization-500x198.jpg","width":500,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization-500x198.jpg"},"full":{"file":"Radicalization.jpg","width":500,"height":266,"mime_type":"image\/jpeg","source_url":"https:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":null,"source_url":"https:\/\/blogg.hiof.no\/fro\/files\/2016\/02\/Radicalization.jpg","_links":{"self":[{"href":"https:\/\/blogg.hiof.no\/fro\/wp-json\/wp\/v2\/media\/370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogg.hiof.no\/fro\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/blogg.hiof.no\/fro\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/blogg.hiof.no\/fro\/wp-json\/wp\/v2\/users\/243"}],"replies":[{"embeddable":true,"href":"https:\/\/blogg.hiof.no\/fro\/wp-json\/wp\/v2\/comments?post=370"}]}}